{"id":19999,"date":"2024-12-04T11:25:32","date_gmt":"2024-12-04T17:25:32","guid":{"rendered":"https:\/\/colitatube.cc\/?p=19999"},"modified":"2026-06-26T14:27:30","modified_gmt":"2026-06-26T20:27:30","slug":"shownoid-mako-chan-02-02sin-censurasubtitulado-en-espanoldescarga-mega-online","status":"publish","type":"post","link":"https:\/\/colitatube.cc\/ru\/shownoid-mako-chan-02-02sin-censurasubtitulado-en-espanoldescarga-mega-online\/","title":{"rendered":"Shownoid Mako-chan [02\/02][Sin Censura][Subtitulado en Espa\u00f1ol][Descarga Mega] Online"},"content":{"rendered":"<p><strong>Makoto es una estudiante de instituto que est\u00e1 follando con su novio Teikeiru cuando de repente recibe una alerta de su ayudante &#8212; la diab\u00f3lica mujer malvada ha tomado a jovencitos como rehenes. Entonces, Makoto se transforma en una hero\u00edna m\u00e1gica y va a luchar contra ella, prometiendo volver para acabar lo que empezaron. Olvidando sus pantaletas, Taikeiru va en su busca con su motocicleta. Desafortunadamente, la pelea de Makoto no marcha bien y la mujer malvada le corta la cabeza. Destrozado, Tei se lleva la cabeza y el cuerpo al laboratorio del profesor (que conoc\u00eda su secreto) y su asistente crea el cuerpo de un androide con apariencia femenina y le transfiere la mente de Makoto. Una vez completada la operaci\u00f3n, Makoto recuerda los \u00faltimos momentos de su vida y busca a su novio para terminar lo que empezaron&#8230;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Makoto es una estudiante de instituto que est\u00e1 follando con su novio Teikeiru cuando de repente recibe una alerta de su ayudante &#8212; la diab\u00f3lica mujer malvada ha tomado a jovencitos como rehenes. Entonces, Makoto se transforma en una hero\u00edna m\u00e1gica y va a luchar contra ella, prometiendo volver para acabar lo que empezaron. Olvidando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","title_seo_single":"Shownoid Mako-chan [02\/02][Sin Censura][Subtitulado en Espa\u00f1ol][Descarga Mega] Online","top_title_seo_page":"","eroz_ads_link":"https:\/\/colitahentai.su\/shownoid-mako-chan-02-02sub-espanolsin-censuramega-online\/","embed":"","duration":"","trailer_url":"","video_optional_1":"","video_optional_2":"","video_optional_3":"","video_optional_4":""},"categories":[39,71],"tags":[275,15,31,113,432,68,169,38,203,67,43,280,33],"toro_pornstar":[],"channel_tt":[269],"quality_tt":[],"class_list":["post-19999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hentai","category-subtitulado-en-espanol","tag-accion","tag-beautiful-girl","tag-blowjob","tag-comedia","tag-escolar","tag-fantasia","tag-gore","tag-masturbacion","tag-nakadashi","tag-romance","tag-sexo-oral","tag-sin-censura","tag-uncensored","channel_tt-y-o-u-c"],"views":796,"_links":{"self":[{"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/posts\/19999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/comments?post=19999"}],"version-history":[{"count":1,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/posts\/19999\/revisions"}],"predecessor-version":[{"id":20006,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/posts\/19999\/revisions\/20006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/media\/20004"}],"wp:attachment":[{"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/media?parent=19999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/categories?post=19999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/tags?post=19999"},{"taxonomy":"toro_pornstar","embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/toro_pornstar?post=19999"},{"taxonomy":"channel_tt","embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/channel_tt?post=19999"},{"taxonomy":"quality_tt","embeddable":true,"href":"https:\/\/colitatube.cc\/ru\/wp-json\/wp\/v2\/quality_tt?post=19999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}